{"id":1271,"date":"2025-01-13T11:57:06","date_gmt":"2025-01-13T10:57:06","guid":{"rendered":"https:\/\/staging.staging.www.alveis.it\/?post_type=product&#038;p=1271"},"modified":"2025-07-14T14:14:58","modified_gmt":"2025-07-14T12:14:58","slug":"apigo","status":"publish","type":"product","link":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/","title":{"rendered":"ApiGo"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1578&#8243; bg_image_phone=&#8221;1581&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-hero&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#faeee0&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;300px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_highlighted_text text_color=&#8221;#000000&#8243; scribble_color=&#8221;#fedc71&#8243; style=&#8221;scribble&#8221; scribble_shape=&#8221;basic-underline&#8221; scribble_thickness=&#8221;regular&#8221; scribble_speed=&#8221;1.3s&#8221; scribble_easing=&#8221;ease_in_out&#8221; text_direction=&#8221;default&#8221;]\n<h1 class=\"text-XL-bold\"><em>ApiGo<\/em><\/h1>\n[\/nectar_highlighted_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-section-two&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#e1f1ff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;245px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;curve_asym&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;first-inner-row&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;\u2014 Mangime complementare per api&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-S-regular padding-bottom-40&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Una spinta alla salute e al benessere delle api&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Mangime in polvere a base di maltodetrine, estratto di lievito e vitamine.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-40&#8243;][\/split_line_heading][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h5&#8243; button_color=&#8221;default&#8221; text_color=&#8221;#ff5500&#8243; text_color_hover=&#8221;#ff5500&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;iconsmind&#8221; link_text=&#8221;Scheda tecnica&#8221; url=&#8221;\/app\/uploads\/2025\/07\/Api-GO-ST-IT-2010.pdf&#8221; icon_iconsmind=&#8221;iconsmind-Download2&#8243; class=&#8221;text-S-medium cta-underline&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1927&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e1f1ff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-section-three&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#e2f3c8&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][tabbed_section style=&#8221;vertical_scrolling&#8221; tab_color=&#8221;Accent-Color&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;0%&#8221; vs_tab_tag=&#8221;p&#8221; vs_cta_style=&#8221;see-through&#8221; vs_cta_bg_color=&#8221;default&#8221; vs_cta_heading_tag=&#8221;h6&#8243; vs_sticky_aspect=&#8221;default&#8221; el_class=&#8221;sticky-tabs-cs&#8221;][tab icon_family=&#8221;none&#8221; title=&#8221;Utilizzo&#8221; id=&#8221;1752490691766-0&#8243; tab_id=&#8221;1752490691767-0&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Come si usa&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Sospendere 20g di prodotto, tutto il contenuto della singola busta monodose, in 1 litro di acqua. Questa soluzione \u00e8 sufficiente al trattamento (una volta) di 20 arnie. Somministrare 50 ml della soluzione cos\u00ec ottenuta, per ogni arnia, gocciolandola tra i favi. Ripetere la somministrazione almeno tre volte a cadenza settimanale.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-80&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Composizione&#8221; id=&#8221;1752490691990-10&#8243; tab_id=&#8221;1752490691991-8&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Composizione&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Glucosio, Maltodestrine, Saccarosio, Estratto di lievito, Antiossidante<br \/>\n(Acido ascorbico).&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-80&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Vantaggi&#8221; id=&#8221;1752490692133-10&#8243; tab_id=&#8221;1752490692134-4&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Vantaggi&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Incrementa le performance dell&#8217;alveare e della forza famiglia.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-32&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Migliora significativamente la compattezza della covata.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-80&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Confezioni&#8221; id=&#8221;1752490692309-4&#8243; tab_id=&#8221;1752490692310-0&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezioni&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold padding-bottom-40&#8243;][\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;confezioni-cs-row&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;791&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-20&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Busta da 20 g, scatola da 10 pezzi&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-80&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Periodo di validit\u00e0&#8221; id=&#8221;1752490692563-5&#8243; tab_id=&#8221;1752490692564-0&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Periodo di validit\u00e0&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold padding-bottom-40&#8243;][\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;validita-cs-row&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;779&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-20&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Consumare preferibilmente entro 12 mesi&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-semi-bold padding-bottom-15&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Dalla data di confezionamento&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-S-regular&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e2f3c8&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;product-section-four&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#faeee0&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;230px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;curve_asym_2&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Domande frequenti&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-L-bold padding-bottom-70&#8243;][\/split_line_heading][image_with_animation image_url=&#8221;645&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-70&#8243;][toggles style=&#8221;minimal&#8221; accordion=&#8221;true&#8221; accordion_starting_functionality=&#8221;default&#8221;][toggle color=&#8221;Accent-Color&#8221; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Ci sono metodi alternativi di somministrazione di ApiGo?&#8221;][vc_column_text text_direction=&#8221;default&#8221;]Si, Il prodotto pu\u00f2 essere somministrato anche spruzzato su adulti e favi; in tal caso se ne consiglia la sospensione in circa 4 litri di acqua, spruzzando ogni alveare con 200 ml della preparazione (ci riferiamo sempre alla dose calcolata per 1 somministrazione per 20 arnie).<br \/>\nAnche con questa modalit\u00e0 ripetere la somministrazione almeno tre volte a cadenza settimanale. Dopo la sospensione in acqua il prodotto va conservato al fresco per non pi\u00f9 di 12 ore.[\/vc_column_text][\/toggle][\/toggles][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h5&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#ff5500&#8243; text_color=&#8221;#ffffff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Scheda tecnica&#8221; class=&#8221;padding-top-60 cta-custom yellow-honey center-cta&#8221; url=&#8221;\/app\/uploads\/2025\/07\/Api-GO-ST-IT-2010.pdf&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1578&#8243; bg_image_phone=&#8221;1581&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;&#8230;<\/p>\n","protected":false},"featured_media":1575,"template":"","meta":[],"product_cat":[126,137],"product_tag":[],"class_list":{"0":"post-1271","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tutti","7":"product_cat-nutrizione","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ApiGo - Alveis<\/title>\n<meta name=\"description\" content=\"ApiGo \u00e8 un mangime complementare per apicoltura a base di maltodestrine, estratto di lievito e vitamine. Scopri come utilizzarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ApiGo - Alveis\" \/>\n<meta property=\"og:description\" content=\"ApiGo \u00e8 un mangime complementare per apicoltura a base di maltodestrine, estratto di lievito e vitamine. Scopri come utilizzarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Alveis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alveisitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T12:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alveis.it\/app\/uploads\/2025\/01\/Alveis_Anteprima_ApiGo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ApiGo - Alveis","description":"ApiGo \u00e8 un mangime complementare per apicoltura a base di maltodestrine, estratto di lievito e vitamine. Scopri come utilizzarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/","og_locale":"it_IT","og_type":"article","og_title":"ApiGo - Alveis","og_description":"ApiGo \u00e8 un mangime complementare per apicoltura a base di maltodestrine, estratto di lievito e vitamine. Scopri come utilizzarlo.","og_url":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/","og_site_name":"Alveis","article_publisher":"https:\/\/www.facebook.com\/alveisitalia","article_modified_time":"2025-07-14T12:14:58+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.alveis.it\/app\/uploads\/2025\/01\/Alveis_Anteprima_ApiGo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/","url":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/","name":"ApiGo - Alveis","isPartOf":{"@id":"https:\/\/www.alveis.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/#primaryimage"},"image":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alveis.it\/app\/uploads\/2025\/01\/Alveis_Anteprima_ApiGo.jpg","datePublished":"2025-01-13T10:57:06+00:00","dateModified":"2025-07-14T12:14:58+00:00","description":"ApiGo \u00e8 un mangime complementare per apicoltura a base di maltodestrine, estratto di lievito e vitamine. Scopri come utilizzarlo.","breadcrumb":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alveis.it\/it\/prodotti\/apigo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/#primaryimage","url":"https:\/\/www.alveis.it\/app\/uploads\/2025\/01\/Alveis_Anteprima_ApiGo.jpg","contentUrl":"https:\/\/www.alveis.it\/app\/uploads\/2025\/01\/Alveis_Anteprima_ApiGo.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.alveis.it\/it\/prodotti\/apigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alveis.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.alveis.it\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"ApiGo"}]},{"@type":"WebSite","@id":"https:\/\/www.alveis.it\/it\/#website","url":"https:\/\/www.alveis.it\/it\/","name":"Alveis","description":"","publisher":{"@id":"https:\/\/www.alveis.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alveis.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.alveis.it\/it\/#organization","name":"Alveis","url":"https:\/\/www.alveis.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveis.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.alveis.it\/app\/uploads\/2024\/04\/alveis-logo.svg","contentUrl":"https:\/\/www.alveis.it\/app\/uploads\/2024\/04\/alveis-logo.svg","width":1,"height":1,"caption":"Alveis"},"image":{"@id":"https:\/\/www.alveis.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alveisitalia","https:\/\/it.linkedin.com\/company\/alveis-chemicals-laif","https:\/\/www.youtube.com\/channel\/UCi91bEOOmuDqFRq9soIsf_A","https:\/\/www.instagram.com\/alveis_chemicalslaif\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product\/1271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/media\/1575"}],"wp:attachment":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/media?parent=1271"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product_cat?post=1271"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product_tag?post=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}