{"id":858,"date":"2024-12-11T08:39:15","date_gmt":"2024-12-11T07:39:15","guid":{"rendered":"https:\/\/staging.staging.www.alveis.it\/?post_type=product&#038;p=858"},"modified":"2025-10-10T10:10:07","modified_gmt":"2025-10-10T08:10:07","slug":"alveisclean","status":"publish","type":"product","link":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/","title":{"rendered":"AlveisClean"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1519&#8243; bg_image_phone=&#8221;1522&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-hero&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#faeee0&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;300px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_highlighted_text text_color=&#8221;#000000&#8243; scribble_color=&#8221;#fedc71&#8243; style=&#8221;scribble&#8221; scribble_shape=&#8221;basic-underline&#8221; scribble_thickness=&#8221;regular&#8221; scribble_speed=&#8221;1.3s&#8221; scribble_easing=&#8221;ease_in_out&#8221; text_direction=&#8221;default&#8221;]\n<h1 class=\"text-XL-bold\"><em>AlveisClean<\/em><\/h1>\n[\/nectar_highlighted_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-section-two&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#e1f1ff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;245px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;curve_asym&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;first-inner-row&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;\u2014 Detergente schiumogeno ad elevata alcalinit\u00e0&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-S-regular padding-bottom-40&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Ideale per la rimozione di propoli e cera d&#8217;api da tutte le superfici&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Assicura un potente effetto sgrassante su tutta l&#8217;attrezzatura apistica. Permette una pulizia accurata anche sulle superfici verticali grazie all&#8217;azione schiumogena.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-40&#8243;][\/split_line_heading][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h5&#8243; button_color=&#8221;default&#8221; text_color=&#8221;#ff5500&#8243; text_color_hover=&#8221;#ff5500&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;iconsmind&#8221; link_text=&#8221;Scheda di sicurezza&#8221; url=&#8221;\/app\/uploads\/2025\/07\/ALVEIS-CLEAN_SS-IT.pdf&#8221; icon_iconsmind=&#8221;iconsmind-Download2&#8243; class=&#8221;text-S-medium cta-underline&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1841&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e1f1ff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;prodotto-section-three&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#e2f3c8&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][tabbed_section style=&#8221;vertical_scrolling&#8221; tab_color=&#8221;Accent-Color&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;0%&#8221; vs_tab_tag=&#8221;p&#8221; vs_cta_style=&#8221;see-through&#8221; vs_cta_bg_color=&#8221;default&#8221; vs_cta_heading_tag=&#8221;h6&#8243; vs_sticky_aspect=&#8221;default&#8221; el_class=&#8221;sticky-tabs-cs&#8221;][tab icon_family=&#8221;none&#8221; title=&#8221;Descrizione&#8221; id=&#8221;1760083780284-5&#8243; tab_id=&#8221;1760083780285-9&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Descrizione prodotto&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;AlveisClean \u00e8 un formulato caratterizzato dalla presenza di alcali e tensioattivi altamente schiumogeni che prolungando l&#8217;azione di contatto con le superfici lo rendono idoneo alla pulizia dei locali di smielatura, parti esterne dei macchinari, tavoli di lavorazione e di tutto il materiale apistico come nutritori, escludi regina, leve, affumicatori etc. Compatibile con tutti i materiali ad esclusione dei metalli leggeri, come l\u2019alluminio o metalli zincati.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40 padding-bottom-80&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Utilizzo&#8221; id=&#8221;1760083780357-3&#8243; tab_id=&#8221;1760083780357-3&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Come si usa&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Diluire da 30 ml a 60 ml di AlveisClean per ogni litro d&#8217;acqua e applicare sulle superfici da pulire manualmente, tramite immersione o spruzzatura o utilizzando apposite lance schiumogene. Lasciare agire il prodotto per almeno 5 minuti o sino a quando si \u00e8 raggiunto il grado di pulizia desiderata, quindi risciacquare abbondantemente.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Consigli per l\u2019utilizzo&#8221; id=&#8221;1760083780394-7&#8243; tab_id=&#8221;1760083780394-7&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;I nostri consigli&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Per velocizzare l&#8217;azione di pulizia di AlveisClean rimuovi lo sporco pi\u00f9 grossolano dalle superfici.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-40&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Per rimuovere lo sporco pi\u00f9 tenace dilata il tempo di contatto con le superfici.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-32&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Il prodotto \u00e8 caustico, indossa indumenti protettivi, guanti e occhiali quando lo usi.&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-regular padding-top-32&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Confezioni&#8221; id=&#8221;1760083780461-5&#8243; tab_id=&#8221;1760083780461-0&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezioni&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-M-bold padding-bottom-40&#8243;][\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;confezioni-cs-row&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;2153&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-20&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Flacone da 1L&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-semi-bold padding-bottom-15&#8243;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;2155&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-20&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Tanica da 5L&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-N-semi-bold padding-bottom-15&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e2f3c8&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;product-section-four&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#faeee0&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;230px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;curve_asym_2&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Domande frequenti&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;text-L-bold padding-bottom-70&#8243;][\/split_line_heading][image_with_animation image_url=&#8221;645&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;padding-bottom-70&#8243;][toggles style=&#8221;minimal&#8221; accordion=&#8221;true&#8221; accordion_starting_functionality=&#8221;default&#8221;][toggle color=&#8221;Accent-Color&#8221; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Posso usare AlveisClean per pulire i locali di smielatura?&#8221;][vc_column_text text_direction=&#8221;default&#8221;]Si, \u00e8 possibile usarlo per pulire superfici, macchinari e attrezzature. Per i contenitori destinati a contenere alimenti \u00e8 indispensabile un accurato risciacquo.[\/vc_column_text][\/toggle][\/toggles][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h5&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#ff5500&#8243; text_color=&#8221;#ffffff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Scheda di sicurezza&#8221; class=&#8221;padding-top-60 cta-custom yellow-honey center-cta&#8221; url=&#8221;\/app\/uploads\/2025\/07\/ALVEIS-CLEAN_SS-IT.pdf&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1519&#8243; bg_image_phone=&#8221;1522&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;&#8230;<\/p>\n","protected":false},"featured_media":1516,"template":"","meta":[],"product_cat":[126,139],"product_tag":[],"class_list":{"0":"post-858","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tutti","7":"product_cat-pulizia-e-igiene","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AlveisClean - Alveis<\/title>\n<meta name=\"description\" content=\"AlveisClean \u00e8 un detergente schiumogeno ad elevata alcalinit\u00e0 indicato per la pulizia e la rimozione di propoli e cera. Scopri come utilizzarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AlveisClean - Alveis\" \/>\n<meta property=\"og:description\" content=\"AlveisClean \u00e8 un detergente schiumogeno ad elevata alcalinit\u00e0 indicato per la pulizia e la rimozione di propoli e cera. Scopri come utilizzarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/\" \/>\n<meta property=\"og:site_name\" content=\"Alveis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alveisitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T08:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alveis.it\/app\/uploads\/2024\/12\/Alveis_Anteprima_AlveisClean.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AlveisClean - Alveis","description":"AlveisClean \u00e8 un detergente schiumogeno ad elevata alcalinit\u00e0 indicato per la pulizia e la rimozione di propoli e cera. Scopri come utilizzarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/","og_locale":"it_IT","og_type":"article","og_title":"AlveisClean - Alveis","og_description":"AlveisClean \u00e8 un detergente schiumogeno ad elevata alcalinit\u00e0 indicato per la pulizia e la rimozione di propoli e cera. Scopri come utilizzarlo.","og_url":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/","og_site_name":"Alveis","article_publisher":"https:\/\/www.facebook.com\/alveisitalia","article_modified_time":"2025-10-10T08:10:07+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.alveis.it\/app\/uploads\/2024\/12\/Alveis_Anteprima_AlveisClean.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/","url":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/","name":"AlveisClean - Alveis","isPartOf":{"@id":"https:\/\/www.alveis.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/#primaryimage"},"image":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alveis.it\/app\/uploads\/2024\/12\/Alveis_Anteprima_AlveisClean.jpg","datePublished":"2024-12-11T07:39:15+00:00","dateModified":"2025-10-10T08:10:07+00:00","description":"AlveisClean \u00e8 un detergente schiumogeno ad elevata alcalinit\u00e0 indicato per la pulizia e la rimozione di propoli e cera. Scopri come utilizzarlo.","breadcrumb":{"@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/#primaryimage","url":"https:\/\/www.alveis.it\/app\/uploads\/2024\/12\/Alveis_Anteprima_AlveisClean.jpg","contentUrl":"https:\/\/www.alveis.it\/app\/uploads\/2024\/12\/Alveis_Anteprima_AlveisClean.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.alveis.it\/it\/prodotti\/alveisclean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alveis.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.alveis.it\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"AlveisClean"}]},{"@type":"WebSite","@id":"https:\/\/www.alveis.it\/it\/#website","url":"https:\/\/www.alveis.it\/it\/","name":"Alveis","description":"","publisher":{"@id":"https:\/\/www.alveis.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alveis.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.alveis.it\/it\/#organization","name":"Alveis","url":"https:\/\/www.alveis.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveis.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.alveis.it\/app\/uploads\/2024\/04\/alveis-logo.svg","contentUrl":"https:\/\/www.alveis.it\/app\/uploads\/2024\/04\/alveis-logo.svg","width":1,"height":1,"caption":"Alveis"},"image":{"@id":"https:\/\/www.alveis.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alveisitalia","https:\/\/it.linkedin.com\/company\/alveis-chemicals-laif","https:\/\/www.youtube.com\/channel\/UCi91bEOOmuDqFRq9soIsf_A","https:\/\/www.instagram.com\/alveis_chemicalslaif\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/media\/1516"}],"wp:attachment":[{"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product_cat?post=858"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alveis.it\/it\/wp-json\/wp\/v2\/product_tag?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}